{"id":7036,"date":"2020-10-10T20:48:23","date_gmt":"2020-10-10T18:48:23","guid":{"rendered":"https:\/\/www.gymnasium-saarburg.de\/hp\/?p=7036"},"modified":"2020-10-10T20:48:23","modified_gmt":"2020-10-10T18:48:23","slug":"herbstferien-in-corona-zeiten","status":"publish","type":"post","link":"https:\/\/www.gymnasium-saarburg.de\/hp\/2020\/10\/10\/herbstferien-in-corona-zeiten\/","title":{"rendered":"Herbstferien in Corona-Zeiten"},"content":{"rendered":"\n<p class=\"silbentrennung\">Die erste Etappe des Schuljahres ist geschafft: Wir haben acht Wochen Unterricht gem\u00e4\u00df Szenario 1 der Landesregierung mehr oder weniger reibungslos hinter uns gebracht, und die verdienten Herbstferien stehen nun vor der T\u00fcr!<\/p>\n\n\n\n<p class=\"silbentrennung\">Wir m\u00f6chten uns an dieser Stelle zun\u00e4chst bei der gesamten Schulgemeinschaft bedanken:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li class=\"silbentrennung\">bei den Lehrkr\u00e4ften f\u00fcr die unter den gegebenen schwierigen Bedingungen geleistete Arbeit und das gro\u00dfe Engagement, sowohl im planm\u00e4\u00dfigen Unterricht als auch in Arbeitsgemeinschaften und Projekten;<\/li><li class=\"silbentrennung\">bei den Eltern f\u00fcr das wohlwollende Verst\u00e4ndnis, das Sie unseren Ma\u00dfnahmen entgegenbringen, und den verantwortungsbewussten Umgang mit Krankmeldungen und Corona-Tests;<\/li><li class=\"silbentrennung\">bei der Sch\u00fclerschaft f\u00fcr die hohe Akzeptanz der manchmal umst\u00e4ndlich anmutenden schulinternen Regeln und die konstruktiven Hinweise.<\/li><\/ul>\n\n\n\n<p class=\"silbentrennung\">Nat\u00fcrlich gibt es auch Kritik an einzelnen Regeln. Und Ma\u00dfnahmen, die den einen bereits \u00fcberfordern, gehen der anderen nicht weit genug. Wir bem\u00fchen uns innerhalb der Schulleitung, m\u00f6glichst viele verschiedene Aspekte zu ber\u00fccksichtigen und abzuw\u00e4gen, bevor wir im Bewusstsein unserer Verantwortung Entscheidungen treffen, von denen wir hoffen, dass sie von der gesamten Schulgemeinschaft mitgetragen werden k\u00f6nnen.<\/p>\n\n\n\n<p class=\"silbentrennung\">Nach den Herbstferien wird uns insbesondere das L\u00fcften der R\u00e4ume vor besondere Herausforderungen stellen. Zudem naht die Erk\u00e4ltungszeit, wobei es m\u00f6glicherweise schwierig sein wird, eine Erk\u00e4ltung von einer Corona-Erkrankung zu unterscheiden. Die unbedingte Einhaltung aller Hygieneregeln und gegenseitige R\u00fccksichtnahme werden deshalb noch wichtiger werden.<\/p>\n\n\n\n<p class=\"silbentrennung\">Obwohl wir durch unser Fernunterrichtskonzept und die gezielte Einweisung der Sch\u00fclerinnen und Sch\u00fcler besser auf eine m\u00f6gliche Schulschlie\u00dfung vorbereitet sind als noch im Fr\u00fchjahr, wollen wir doch gemeinsam hoffen, dass sich diese in der nun sich manifestierenden zweiten Welle wird vermeiden lassen. Insbesondere f\u00fcr unsere zuk\u00fcnftigen Abiturientinnen und Abiturienten sind der Pr\u00e4senzunterricht und die Teilnahme an den Abi-Vorklausuren unverzichtbar.<\/p>\n\n\n\n<p class=\"silbentrennung\">In diesem Sinne w\u00fcnschen wir erholsame Ferien zu Hause und hoffen nat\u00fcrlich, dass wir alle gesund aus den Herbstferien wiederkehren und die n\u00e4chsten acht Unterrichtswochen bis Weihnachten ebenso wohlbehalten \u00fcberstehen werden wie den Schuljahresbeginn.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die erste Etappe des Schuljahres ist geschafft: Wir haben acht Wochen Unterricht gem\u00e4\u00df Szenario 1 der Landesregierung mehr oder weniger reibungslos hinter uns gebracht, und die verdienten Herbstferien stehen nun vor der T\u00fcr! Wir m\u00f6chten uns an dieser Stelle zun\u00e4chst bei der gesamten Schulgemeinschaft bedanken: bei den Lehrkr\u00e4ften f\u00fcr die unter den gegebenen schwierigen Bedingungen geleistete Arbeit und das gro\u00dfe [&#8230;]<\/p>\n","protected":false},"author":13,"featured_media":5616,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,749,23],"tags":[],"coauthors":[289],"class_list":["post-7036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-corona","category-mitteilung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Herbstferien in Corona-Zeiten - Gymnasium Saarburg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gymnasium-saarburg.de\/hp\/2020\/10\/10\/herbstferien-in-corona-zeiten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Herbstferien in Corona-Zeiten - Gymnasium Saarburg\" \/>\n<meta property=\"og:description\" content=\"Die erste Etappe des Schuljahres ist geschafft: Wir haben acht Wochen Unterricht gem\u00e4\u00df Szenario 1 der Landesregierung mehr oder weniger reibungslos hinter uns gebracht, und die verdienten Herbstferien stehen nun vor der T\u00fcr! Wir m\u00f6chten uns an dieser Stelle zun\u00e4chst bei der gesamten Schulgemeinschaft bedanken: bei den Lehrkr\u00e4ften f\u00fcr die unter den gegebenen schwierigen Bedingungen geleistete Arbeit und das gro\u00dfe [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gymnasium-saarburg.de\/hp\/2020\/10\/10\/herbstferien-in-corona-zeiten\/\" \/>\n<meta property=\"og:site_name\" content=\"Gymnasium Saarburg\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-10T18:48:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-content\/uploads\/2019\/09\/herbst_1569577817.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"849\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andreas Schreiner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreas Schreiner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Andreas Schreiner\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/2020\\\/10\\\/10\\\/herbstferien-in-corona-zeiten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/2020\\\/10\\\/10\\\/herbstferien-in-corona-zeiten\\\/\"},\"author\":{\"name\":\"Andreas Schreiner\",\"@id\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/#\\\/schema\\\/person\\\/668cf78dd43623ce6f5241a1528b27c9\"},\"headline\":\"Herbstferien in Corona-Zeiten\",\"datePublished\":\"2020-10-10T18:48:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/2020\\\/10\\\/10\\\/herbstferien-in-corona-zeiten\\\/\"},\"wordCount\":340,\"image\":{\"@id\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/2020\\\/10\\\/10\\\/herbstferien-in-corona-zeiten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/herbst_1569577817.jpg\",\"articleSection\":{\"1\":\"Corona\",\"2\":\"Mitteilung\"},\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/2020\\\/10\\\/10\\\/herbstferien-in-corona-zeiten\\\/\",\"url\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/2020\\\/10\\\/10\\\/herbstferien-in-corona-zeiten\\\/\",\"name\":\"Herbstferien in Corona-Zeiten - Gymnasium Saarburg\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/2020\\\/10\\\/10\\\/herbstferien-in-corona-zeiten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/2020\\\/10\\\/10\\\/herbstferien-in-corona-zeiten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/herbst_1569577817.jpg\",\"datePublished\":\"2020-10-10T18:48:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/#\\\/schema\\\/person\\\/668cf78dd43623ce6f5241a1528b27c9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/2020\\\/10\\\/10\\\/herbstferien-in-corona-zeiten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/2020\\\/10\\\/10\\\/herbstferien-in-corona-zeiten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/2020\\\/10\\\/10\\\/herbstferien-in-corona-zeiten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/herbst_1569577817.jpg\",\"contentUrl\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/herbst_1569577817.jpg\",\"width\":1280,\"height\":849,\"caption\":\"giani \\\/ Pixabay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/2020\\\/10\\\/10\\\/herbstferien-in-corona-zeiten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Herbstferien in Corona-Zeiten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/#website\",\"url\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/\",\"name\":\"Gymnasium Saarburg\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/#\\\/schema\\\/person\\\/668cf78dd43623ce6f5241a1528b27c9\",\"name\":\"Andreas Schreiner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/100ab0342f9e55ddf58128f16f2af2e5ad761b712bbab6b5f19294cebde09965?s=96&d=mm&r=gc29336ee8f6afd8e1a6d5e823b0d81c3\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/100ab0342f9e55ddf58128f16f2af2e5ad761b712bbab6b5f19294cebde09965?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/100ab0342f9e55ddf58128f16f2af2e5ad761b712bbab6b5f19294cebde09965?s=96&d=mm&r=g\",\"caption\":\"Andreas Schreiner\"},\"url\":\"https:\\\/\\\/www.gymnasium-saarburg.de\\\/hp\\\/author\\\/sr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Herbstferien in Corona-Zeiten - Gymnasium Saarburg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gymnasium-saarburg.de\/hp\/2020\/10\/10\/herbstferien-in-corona-zeiten\/","og_locale":"de_DE","og_type":"article","og_title":"Herbstferien in Corona-Zeiten - Gymnasium Saarburg","og_description":"Die erste Etappe des Schuljahres ist geschafft: Wir haben acht Wochen Unterricht gem\u00e4\u00df Szenario 1 der Landesregierung mehr oder weniger reibungslos hinter uns gebracht, und die verdienten Herbstferien stehen nun vor der T\u00fcr! Wir m\u00f6chten uns an dieser Stelle zun\u00e4chst bei der gesamten Schulgemeinschaft bedanken: bei den Lehrkr\u00e4ften f\u00fcr die unter den gegebenen schwierigen Bedingungen geleistete Arbeit und das gro\u00dfe [...]","og_url":"https:\/\/www.gymnasium-saarburg.de\/hp\/2020\/10\/10\/herbstferien-in-corona-zeiten\/","og_site_name":"Gymnasium Saarburg","article_published_time":"2020-10-10T18:48:23+00:00","og_image":[{"width":1280,"height":849,"url":"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-content\/uploads\/2019\/09\/herbst_1569577817.jpg","type":"image\/jpeg"}],"author":"Andreas Schreiner","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Andreas Schreiner","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten","Written by":"Andreas Schreiner"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.gymnasium-saarburg.de\/hp\/2020\/10\/10\/herbstferien-in-corona-zeiten\/#article","isPartOf":{"@id":"https:\/\/www.gymnasium-saarburg.de\/hp\/2020\/10\/10\/herbstferien-in-corona-zeiten\/"},"author":{"name":"Andreas Schreiner","@id":"https:\/\/www.gymnasium-saarburg.de\/hp\/#\/schema\/person\/668cf78dd43623ce6f5241a1528b27c9"},"headline":"Herbstferien in Corona-Zeiten","datePublished":"2020-10-10T18:48:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gymnasium-saarburg.de\/hp\/2020\/10\/10\/herbstferien-in-corona-zeiten\/"},"wordCount":340,"image":{"@id":"https:\/\/www.gymnasium-saarburg.de\/hp\/2020\/10\/10\/herbstferien-in-corona-zeiten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-content\/uploads\/2019\/09\/herbst_1569577817.jpg","articleSection":{"1":"Corona","2":"Mitteilung"},"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.gymnasium-saarburg.de\/hp\/2020\/10\/10\/herbstferien-in-corona-zeiten\/","url":"https:\/\/www.gymnasium-saarburg.de\/hp\/2020\/10\/10\/herbstferien-in-corona-zeiten\/","name":"Herbstferien in Corona-Zeiten - Gymnasium Saarburg","isPartOf":{"@id":"https:\/\/www.gymnasium-saarburg.de\/hp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gymnasium-saarburg.de\/hp\/2020\/10\/10\/herbstferien-in-corona-zeiten\/#primaryimage"},"image":{"@id":"https:\/\/www.gymnasium-saarburg.de\/hp\/2020\/10\/10\/herbstferien-in-corona-zeiten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-content\/uploads\/2019\/09\/herbst_1569577817.jpg","datePublished":"2020-10-10T18:48:23+00:00","author":{"@id":"https:\/\/www.gymnasium-saarburg.de\/hp\/#\/schema\/person\/668cf78dd43623ce6f5241a1528b27c9"},"breadcrumb":{"@id":"https:\/\/www.gymnasium-saarburg.de\/hp\/2020\/10\/10\/herbstferien-in-corona-zeiten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gymnasium-saarburg.de\/hp\/2020\/10\/10\/herbstferien-in-corona-zeiten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.gymnasium-saarburg.de\/hp\/2020\/10\/10\/herbstferien-in-corona-zeiten\/#primaryimage","url":"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-content\/uploads\/2019\/09\/herbst_1569577817.jpg","contentUrl":"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-content\/uploads\/2019\/09\/herbst_1569577817.jpg","width":1280,"height":849,"caption":"giani \/ Pixabay"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gymnasium-saarburg.de\/hp\/2020\/10\/10\/herbstferien-in-corona-zeiten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.gymnasium-saarburg.de\/hp\/"},{"@type":"ListItem","position":2,"name":"Herbstferien in Corona-Zeiten"}]},{"@type":"WebSite","@id":"https:\/\/www.gymnasium-saarburg.de\/hp\/#website","url":"https:\/\/www.gymnasium-saarburg.de\/hp\/","name":"Gymnasium Saarburg","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gymnasium-saarburg.de\/hp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.gymnasium-saarburg.de\/hp\/#\/schema\/person\/668cf78dd43623ce6f5241a1528b27c9","name":"Andreas Schreiner","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/100ab0342f9e55ddf58128f16f2af2e5ad761b712bbab6b5f19294cebde09965?s=96&d=mm&r=gc29336ee8f6afd8e1a6d5e823b0d81c3","url":"https:\/\/secure.gravatar.com\/avatar\/100ab0342f9e55ddf58128f16f2af2e5ad761b712bbab6b5f19294cebde09965?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/100ab0342f9e55ddf58128f16f2af2e5ad761b712bbab6b5f19294cebde09965?s=96&d=mm&r=g","caption":"Andreas Schreiner"},"url":"https:\/\/www.gymnasium-saarburg.de\/hp\/author\/sr\/"}]}},"_links":{"self":[{"href":"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-json\/wp\/v2\/posts\/7036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-json\/wp\/v2\/comments?post=7036"}],"version-history":[{"count":4,"href":"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-json\/wp\/v2\/posts\/7036\/revisions"}],"predecessor-version":[{"id":7040,"href":"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-json\/wp\/v2\/posts\/7036\/revisions\/7040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-json\/wp\/v2\/media\/5616"}],"wp:attachment":[{"href":"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-json\/wp\/v2\/media?parent=7036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-json\/wp\/v2\/categories?post=7036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-json\/wp\/v2\/tags?post=7036"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.gymnasium-saarburg.de\/hp\/wp-json\/wp\/v2\/coauthors?post=7036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}